{"id":505,"date":"2024-07-24T17:24:35","date_gmt":"2024-07-24T17:24:35","guid":{"rendered":"https:\/\/idarriba.com\/?p=505"},"modified":"2024-09-21T15:36:58","modified_gmt":"2024-09-21T15:36:58","slug":"new-tariff-for-trademark-applications-with-oppositions","status":"publish","type":"post","link":"https:\/\/idarriba.com\/es\/new-tariff-for-trademark-applications-with-oppositions\/","title":{"rendered":"Nuevo arancel para las solicitudes de marcas con oposiciones en Argentina"},"content":{"rendered":"<p>El d\u00eda 10 de julio de 2024, el Instituto Nacional de la Propiedad Industrial (INPI) public\u00f3 la <a href=\"https:\/\/www.boletinoficial.gob.ar\/detalleAviso\/primera\/311064\/20240723\" data-type=\"link\" data-id=\"https:\/\/www.boletinoficial.gob.ar\/detalleAviso\/primera\/311064\/20240723\" target=\"_blank\" rel=\"noreferrer noopener\">Resoluci\u00f3n 295\/2024 ,<\/a>la cual introduce un nuevo arancel en aquellas solicitudes de marcas que reciben oposiciones en Argentina.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Desde ahora, los solicitantes deber\u00e1n abonar una tarifa obligatoria para que el INPI resuelva las oposiciones bajo pena de rechazo autom\u00e1tico de la solicitud de marca.<\/p>\n\n\n<a class=\"wp-block-read-more\" href=\"https:\/\/idarriba.com\/es\/new-tariff-for-trademark-applications-with-oppositions\/\" target=\"_self\">Leer m\u00e1s<span class=\"screen-reader-text\">: New tariff for trademark applications with oppositions<\/span><\/a>\n\n\n<p>El fundamento de esta medida se encuentra en la gran cantidad de oposiciones mantenidas que no han recibido respuesta de los solicitantes de marcas, demostrando un claro desinter\u00e9s de parte de los solicitantes.<\/p>\n\n\n\n<p>La resoluci\u00f3n tambi\u00e9n incluye una cl\u00e1usula transitoria, de aplicaci\u00f3n a las solicitudes con oposiciones pendientes, instando a los solicitantes a pagar el arancel o atenerse al rechazo de la solicitud.<\/p>\n\n\n\n<p>If you have any questions or need clarification, you can contact us at <a href=\"mailto:info@idarriba.com\">info@idarriba.com<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>On July 10, 2024, the National Institute of Industrial Property (INPI) published Resolution 295\/2024, which introduces a new tariff on those trademark applications that receive oppositions in Argentina.<\/p>","protected":false},"author":2,"featured_media":511,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[1],"tags":[42,43],"class_list":["post-505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ip","tag-oposicion-2","tag-opposition"],"_links":{"self":[{"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/posts\/505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/comments?post=505"}],"version-history":[{"count":4,"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/posts\/505\/revisions"}],"predecessor-version":[{"id":546,"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/posts\/505\/revisions\/546"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/media\/511"}],"wp:attachment":[{"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/media?parent=505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/categories?post=505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/tags?post=505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}