{"id":513,"date":"2024-07-20T15:01:00","date_gmt":"2024-07-20T15:01:00","guid":{"rendered":"https:\/\/idarriba.com\/?p=513"},"modified":"2025-05-03T19:29:16","modified_gmt":"2025-05-03T19:29:16","slug":"main-points-of-the-implementation-of-inpi-resolution-p-295-24","status":"publish","type":"post","link":"https:\/\/idarriba.com\/es\/main-points-of-the-implementation-of-inpi-resolution-p-295-24\/","title":{"rendered":"Puntos principales de la implementaci\u00f3n de la Resoluci\u00f3n INPI P-295\/24"},"content":{"rendered":"<p>Los puntos principales de la Implementaci\u00f3n de la Resoluci\u00f3n INPI P-295\/24, son:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>1.\tEmisi\u00f3n de Disposici\u00f3n de DNM (Intimaci\u00f3n al Pago)<\/strong><br>o\tSe dictar\u00e1 una disposici\u00f3n para intimar a los titulares de solicitudes con oposiciones mantenidas, por un plazo de 15 d\u00edas h\u00e1biles.<br>o\tAbarca a quienes no han respondido a la vista de traslado de oposiciones y cuya oposici\u00f3n no tiene dictamen emitido.<br>o\tDisposiciones semanales se emitir\u00e1n con aproximadamente 3000 casos.<\/li>\n\n\n\n<li><strong>2.\tNotificaci\u00f3n por Publicaci\u00f3n en el Bolet\u00edn de Marcas<\/strong><br>o\tA partir del 14 de agosto de 2024, y todos los mi\u00e9rcoles siguientes, se publicar\u00e1n las disposiciones de intimaci\u00f3n en el Bolet\u00edn de Resoluci\u00f3n de Oposiciones.<\/li>\n\n\n\n<li><strong>3.\tPago del Nuevo Arancel por escritos de oposici\u00f3n<\/strong><br>o\tLos solicitantes intimados deber\u00e1n pagar el arancel correspondiente (C\u00f3digo 170.000) a trav\u00e9s del portal de tr\u00e1mites web.<br>o\tEste arancel es \u00fanico por cada solicitud, independientemente del n\u00famero de oposiciones vigentes.<br>o\tEl arancel estar\u00e1 operativo a partir de la semana del 5 de agosto, pero no debe pagarse hasta ser notificado en el Bolet\u00edn de Oposiciones.<\/li>\n\n\n\n<li><strong>4.\tDenegatoria de Solicitudes sin el Correspondiente Pago<\/strong><br>o\tLa Direcci\u00f3n Nacional de Marcas denegar\u00e1 las solicitudes sin el pago del nuevo arancel, emitiendo la disposici\u00f3n correspondiente.<\/li>\n\n\n\n<li><strong>5.\tSuspensi\u00f3n de nuevos traslados de Oposiciones Mantenidas.<\/strong>No se notificar\u00e1n nuevos traslados de oposiciones mantenidas hasta finalizar las intimaciones mencionadas.<\/li>\n<\/ol>","protected":false},"excerpt":{"rendered":"<p>Los puntos principales de la Implementaci\u00f3n de la Resoluci\u00f3n INPI P-295\/24, son:<\/p>","protected":false},"author":2,"featured_media":304,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[1,6],"tags":[29,24,42,43,7],"class_list":["post-513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ip","category-trademarks","tag-inpi","tag-marcas","tag-oposicion-2","tag-opposition","tag-trademarks"],"_links":{"self":[{"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/posts\/513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/comments?post=513"}],"version-history":[{"count":2,"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/posts\/513\/revisions"}],"predecessor-version":[{"id":618,"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/posts\/513\/revisions\/618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/media\/304"}],"wp:attachment":[{"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/media?parent=513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/categories?post=513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/idarriba.com\/es\/wp-json\/wp\/v2\/tags?post=513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}